{"id":377,"date":"2026-03-28T15:17:14","date_gmt":"2026-03-28T14:17:14","guid":{"rendered":"https:\/\/denis-meunier.be\/NosVehicules\/?p=377"},"modified":"2026-03-31T21:08:15","modified_gmt":"2026-03-31T19:08:15","slug":"premieres-impressions","status":"publish","type":"post","link":"https:\/\/denis-meunier.be\/NosVehicules\/2026\/03\/28\/premieres-impressions\/","title":{"rendered":"Premi\u00e8res impressions &#8230;"},"content":{"rendered":"\n<img loading=\"lazy\" decoding=\"async\" width=\"110\" height=\"58\" src=\"https:\/\/denis-meunier.be\/NosVehicules\/wp-content\/uploads\/2026\/03\/1000040068.png\" class=\"attachment-full size-full\" alt=\"\" \/>\n\n\n\n<h2 class=\"wp-block-heading\">Les 1250 premiers KM &#8230;<\/h2>\n\n\n\n<p>En gros, les premi\u00e8res exp\u00e9riences et ressentis. Dans les articles suivants, je m&rsquo;attacherais \u00e0 des d\u00e9tails plus cibl\u00e9s, comme la recharge, les fonctions de l&rsquo;\u00e9cran tactile, &#8230;<\/p>\n\n\n\n<h1 class=\"wp-block-heading\">&#x1f44d;<sub>on appr\u00e9cie :<\/sub><\/h1>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Le confort et les \u00e9quipements sont bien au rendez-vous. Si\u00e8ges Bacquets bien enveloppants &#8211; c\u00f4t\u00e9 chauffeur : r\u00e9glable \u00e0 3 directions (passager 2 directions &#x1f612;)<\/li>\n\n\n\n<li>Le silence de l&rsquo;\u00e9lectrique (surtout en ville)  ;<\/li>\n\n\n\n<li>C&rsquo;est une bonne petite voiture pour la ville ; <\/li>\n\n\n\n<li>En rodage pour 2000 KM, on utilise surtout le mode \u00ab\u00a0<strong>Eco<\/strong>\u00a0\u00bb &#8211; mais il nous convient ;<\/li>\n\n\n\n<li>Quand il le faut, les d\u00e9marrages sont bien ceux d&rsquo;une \u00ab\u00a0\u00e9lectrique\u00a0\u00bb et laissent les \u00ab\u00a0thermiques\u00a0\u00bb bien \u00e0 l&rsquo;arri\u00e8re ;<\/li>\n\n\n\n<li>Les &lsquo;outils&rsquo; de s\u00e9curit\u00e9 et d&rsquo;aide \u00e0 la conduite sont nombreux : surveillance de l&rsquo;attention du conducteur, franchissement de lignes, cam\u00e9ra avant avec d\u00e9tection v\u00e9hicule, pi\u00e9ton ou obstacle, cam\u00e9ra lat\u00e9rale et cam\u00e9ra arri\u00e8re avec radar aide stationnement &#8230;<\/li>\n\n\n\n<li>en r\u00e9sum\u00e9, parfaite comme seconde voiture de ville.<\/li>\n<\/ul>\n\n\n\n<h1 class=\"wp-block-heading\">&#x1f44e;<sub>peut mieux faire &#8230;<\/sub><\/h1>\n\n\n\n<ul class=\"wp-block-list\">\n<li>L&rsquo;autonomie annonc\u00e9e est bien en dessous de la r\u00e9alit\u00e9 ; <em>sur autoroute, <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-medium-pink-color\">200<\/mark> <\/strong>Km max \u00e0 105 Km\/h<\/em> &#8211;<strong> Ce n&rsquo;est pas un v\u00e9hicule taill\u00e9 pour faire de longs trajets<\/strong> ;<\/li>\n\n\n\n<li>Sur autoroute, le syst\u00e8me \u00ab\u00a0Lijn Assist\u00a0\u00bb est tr\u00e8s brutal et provoque des brusques coups de volant pour vous ramener au milieu de la voie de circulation. (faut peut-\u00eatre s&rsquo;habituer)<\/li>\n\n\n\n<li>Les pneus sont bruyants sur certains rev\u00eatements routiers (\u00e0 vive allure)<\/li>\n\n\n\n<li>La recharge de la batterie est longue : <strong>( vous pouvez suivre <a href=\"https:\/\/www.spritmonitor.de\/fr\/detail\/1705870.html\" target=\"_blank\" rel=\"noreferrer noopener\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-medium-pink-color\">ICI<\/mark><\/a>, les sessions de recharge et leurs co\u00fbts. &#8211; Mise \u00e0 jour r\u00e9guli\u00e8re)<\/strong><\/li>\n\n\n\n<li>La couleur noire est tr\u00e8s belle ( et nous assumons notre choix) mais salissante. Nous avons command\u00e9 des bavettes de roue (en attente de livraison) ;<\/li>\n\n\n\n<li>Pas d&rsquo;essuie-glace arri\u00e8re &#x1fae2;<\/li>\n\n\n\n<li>Il y a encore beaucoup \u00e0 apprendre\/d\u00e9couvrir en analysant le mode d&#8217;emploi &#8211; 224 pages &#8211; qui n&rsquo;est pas des plus clair ou pr\u00e9cis (traduction du chinois)<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">A suivre !<\/h2>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les 1250 premiers KM &#8230; En gros, les premi\u00e8res exp\u00e9riences et ressentis. Dans les articles suivants, je m&rsquo;attacherais \u00e0 des d\u00e9tails plus cibl\u00e9s, comme la recharge, les fonctions de l&rsquo;\u00e9cran tactile, &#8230; &#x1f44d;on appr\u00e9cie : &#x1f44e;peut mieux faire &#8230; A suivre !<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-377","post","type-post","status-publish","format-standard","hentry","category-le-byd-dolphin-surf"],"_links":{"self":[{"href":"https:\/\/denis-meunier.be\/NosVehicules\/wp-json\/wp\/v2\/posts\/377","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/denis-meunier.be\/NosVehicules\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/denis-meunier.be\/NosVehicules\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/denis-meunier.be\/NosVehicules\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/denis-meunier.be\/NosVehicules\/wp-json\/wp\/v2\/comments?post=377"}],"version-history":[{"count":4,"href":"https:\/\/denis-meunier.be\/NosVehicules\/wp-json\/wp\/v2\/posts\/377\/revisions"}],"predecessor-version":[{"id":411,"href":"https:\/\/denis-meunier.be\/NosVehicules\/wp-json\/wp\/v2\/posts\/377\/revisions\/411"}],"wp:attachment":[{"href":"https:\/\/denis-meunier.be\/NosVehicules\/wp-json\/wp\/v2\/media?parent=377"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/denis-meunier.be\/NosVehicules\/wp-json\/wp\/v2\/categories?post=377"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/denis-meunier.be\/NosVehicules\/wp-json\/wp\/v2\/tags?post=377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}