{"id":216,"date":"2011-02-28T20:51:00","date_gmt":"2011-02-28T19:51:00","guid":{"rendered":"https:\/\/denis-meunier.be\/Tiguan\/?p=216"},"modified":"2026-03-28T17:03:07","modified_gmt":"2026-03-28T16:03:07","slug":"le-s-max-de-ford","status":"publish","type":"post","link":"https:\/\/denis-meunier.be\/NosVehicules\/2011\/02\/28\/le-s-max-de-ford\/","title":{"rendered":"Le S-Max de Ford"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">2006 -&gt; 2011<\/h2>\n\n\n\n<h2 class=\"wp-block-heading has-light-gray-background-color has-background\">Nous avons tellement rencontr\u00e9 des soucis avec ce v\u00e9hicule que, juste apr\u00e8s son achat, nous avons d\u00e9cid\u00e9 de cr\u00e9er un premier un blog complet pour ce v\u00e9hicule. <br><a href=\"https:\/\/denis-meunier.be\/smax\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0);color:#f90223\" class=\"has-inline-color\">A DECOUVRIR ICI<\/mark><\/strong><\/a><\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><a href=\"https:\/\/denis-meunier.be\/smax\/\" target=\"_blank\" rel=\" noreferrer noopener\"><img decoding=\"async\" src=\"https:\/\/denis-meunier.be\/smax\/wp-content\/uploads\/2007\/05\/dyn003_original_500_375_pjpeg_2569915_78fc469d57c3d234700ee45b8465518f.jpg\" alt=\"\"\/><\/a><\/figure>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>2006 -&gt; 2011 Nous avons tellement rencontr\u00e9 des soucis avec ce v\u00e9hicule que, juste apr\u00e8s son achat, nous avons d\u00e9cid\u00e9 de cr\u00e9er un premier un blog complet pour ce v\u00e9hicule. A DECOUVRIR ICI<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-216","post","type-post","status-publish","format-standard","hentry","category-le-s-max"],"_links":{"self":[{"href":"https:\/\/denis-meunier.be\/NosVehicules\/wp-json\/wp\/v2\/posts\/216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/denis-meunier.be\/NosVehicules\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/denis-meunier.be\/NosVehicules\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/denis-meunier.be\/NosVehicules\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/denis-meunier.be\/NosVehicules\/wp-json\/wp\/v2\/comments?post=216"}],"version-history":[{"count":4,"href":"https:\/\/denis-meunier.be\/NosVehicules\/wp-json\/wp\/v2\/posts\/216\/revisions"}],"predecessor-version":[{"id":390,"href":"https:\/\/denis-meunier.be\/NosVehicules\/wp-json\/wp\/v2\/posts\/216\/revisions\/390"}],"wp:attachment":[{"href":"https:\/\/denis-meunier.be\/NosVehicules\/wp-json\/wp\/v2\/media?parent=216"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/denis-meunier.be\/NosVehicules\/wp-json\/wp\/v2\/categories?post=216"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/denis-meunier.be\/NosVehicules\/wp-json\/wp\/v2\/tags?post=216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}