{"id":134,"date":"2012-07-02T16:58:25","date_gmt":"2012-07-02T14:58:25","guid":{"rendered":"https:\/\/deonisios.wordpress.com\/?p=134"},"modified":"2020-06-03T12:17:39","modified_gmt":"2020-06-03T10:17:39","slug":"le-1er-mai","status":"publish","type":"post","link":"https:\/\/denis-meunier.be\/Deonisios\/2012\/07\/02\/le-1er-mai\/","title":{"rendered":"Le 1er Mai"},"content":{"rendered":"<p><i><b>( Edito de &lsquo;Secouez-vous les id\u00e9es&rsquo; n\u00b0 90 juin juillet ao\u00fbt 2012 &#8211; CESEP &#8211; <a href=\"mailto:info@cesep.be\">info@cesep.be<\/a>)<\/b><\/i><\/p>\n<h4><b>Monsieur Charles,<\/b><\/h4>\n<p>Franchement, sinc\u00e8rement, j&rsquo;envie votre papa. Qu&rsquo;il doit \u00eatre doux pour ce p\u00e8re Louis de ressentir un tel respect filial. Avoir un fils qui suit ses pas aussi fid\u00e8lement. Du berceau \u00e0 la pr\u00e9sidence du MR, du ballon rond au ma\u00eforat, quel beau parcours sur les traces de son papa. Cependant Monsieur Charles, point trop n&rsquo;en faut. Tout n&rsquo;est pas bon \u00e0 prendre, m\u00eame chez un tel papa. Pourquoi diable allez faire le mariole dans les rues de Jodoigne en se faisant passer pour ce qu&rsquo;on n&rsquo;est pas. Pire, en l\u00e9gitimant ce carnaval par une r\u00e9vision de l&rsquo;histoire.<\/p>\n<p>\u00a0\u00bb Le 1er mai, c&rsquo;est nous ! \u00a0\u00bb Franchement, dans votre cas, pour affirmer cela, il faut avoir forc\u00e9 sur le pecket de la province voisine. \u00a0\u00bb Le MR est le d\u00e9l\u00e9gu\u00e9 syndical de ceux qui bossent, qui en veulent&#8230; \u00a0\u00bb L\u00e0, vous fumez autre chose que des Gauloises bleues. \u00a0\u00bb Le premier mai, une f\u00eate authentiquement, typiquement lib\u00e9rale &#8230;\u00a0\u00bb. Franchement, \u00e0 Bruxelles on dirait \u00a0\u00bb ce pe\u00ef est maf \u00ab\u00a0, ce qui se traduit par \u00a0\u00bb ce type est pas un peu fou dans sa t\u00eate \u00a0\u00bb ou encore \u00a0\u00bb Monsieur Charles est bon pour Titeca \u00ab\u00a0. Je rigole mais pour tout vous dire, je vous trouve choquant.<\/p>\n<p>Le 1er mai est la \u00a0\u00bb F\u00eate des Travailleurs \u00a0\u00bb et non pas la \u00a0\u00bb F\u00eate du Travail \u00ab\u00a0. Cette derni\u00e8re appellation a \u00e9t\u00e9 introduite en France par le mar\u00e9chal P\u00e9tain durant le r\u00e9gime de Vichy. Franchement&#8230;c&rsquo;est suspect. Elle est depuis utilis\u00e9e fallacieusement par les&#8230;conservateurs. C&rsquo;est de vous que l&rsquo;on parle, que cela vous plaise ou non, il faut appeler un chat un chat. Je vous \u00e9pargnerai toute l&rsquo;histoire de ce premier mai. Retenez cependant qu&rsquo;elle comm\u00e9more la lutte pour un acquis fondamental de la classe ouvri\u00e8re : la journ\u00e9e des huit heures. Ce sont les syndicats et la IIeme Internationale Socialiste qui ont oeuvr\u00e9 pour cela. Aux USA, des travailleurs ont \u00e9t\u00e9 tu\u00e9s, emprisonn\u00e9s, ex\u00e9cut\u00e9s pour cette revendication. En France, le premier mai 1891 a tourn\u00e9 au drame \u00e0 Fourmies quand la troupe a tir\u00e9 sur la foule, tuant 10 personnes. Croyez-vous que la lutte s&rsquo;est arr\u00eat\u00e9e l\u00e0 ? Que, magnanimes, vos anc\u00eatres lib\u00e9raux ont accord\u00e9 la journ\u00e9e des 8 heures ? En France, il a fallu attendre 1919 et en Belgique la loi du 14 juin 1921.<\/p>\n<p>Non Monsieur Charles, le MR n&rsquo;est pas \u00a0\u00bb le d\u00e9l\u00e9gu\u00e9 syndical de ceux qui bossent \u00ab\u00a0. Estimez-vous que les d\u00e9l\u00e9gu\u00e9s des entreprises, les vrais, les \u00e9lus des travailleurs, d\u00e9fendent des fain\u00e9ants qui ne prennent pas leur travail au s\u00e9rieux ? On bosse dans les entreprises Monsieur Charles, beaucoup, souvent trop, regardez les \u00e9tudes m\u00e9dicales. Vous voulez \u00eatre d\u00e9l\u00e9gu\u00e9 syndical ? Eclairez-nous alors sur la position du MR par rapport \u00e0 la repr\u00e9sentativit\u00e9 des travailleurs dans les PME. Pas facile hein ! Vous ne serez jamais d\u00e9l\u00e9gu\u00e9 syndical. On ne peut d\u00e9fendre le droit de gr\u00e8ve et revendiquer le service minimum. On ne peut d\u00e9fendre le travailleur et demander plus de flexibilit\u00e9 du march\u00e9 du travail. On ne peut d\u00e9fendre le travailleur et pr\u00f4ner la diminution des allocations de ch\u00f4mage dans le temps. On ne peut d\u00e9fendre le travailleur et traiter \u00a0\u00bb d&rsquo;assist\u00e9 \u00a0\u00bb celui qui perd son emploi, qu&rsquo;il \u00a0\u00bb en veuille \u00a0\u00bb comme vous dites, ou pas. On ne peut tout simplement pas d\u00e9fendre le travailleur et m\u00e9priser celui qui ne trouve pas d&#8217;emploi quand il n&rsquo;y en a pas !<\/p>\n<p>Seriez-vous le d\u00e9l\u00e9gu\u00e9 syndical des ind\u00e9pendants, des professions lib\u00e9rales, des PME ? C&rsquo;est votre fonds de commerce, depuis des ann\u00e9es. Je doute cependant de votre efficacit\u00e9 envers eux. Ecrivez leur, faites une belle lettre, une vraie, avec du sens. Pas la missive banale et creuse que l&rsquo;on trouve sur le site du MR, intitul\u00e9e \u00a0\u00bb 7 h 22 sur l&rsquo;E411 \u00a0\u00bb et dat\u00e9e du 1er mai. Expliquez \u00e0 vos admirateurs pourquoi, lors de la derni\u00e8re r\u00e9forme fiscale, vous avez particuli\u00e8rement soign\u00e9 les plus riches d&rsquo;entre eux au d\u00e9triment du plus grand nombre. Expliquez aux patrons de PME, vous savez, \u00a0\u00bb ceux qui bossent \u00ab\u00a0, pourquoi leur soci\u00e9t\u00e9 paie autant d&rsquo;imp\u00f4ts quand de toutes grosses entreprises, qui font des milliards de b\u00e9n\u00e9fices, n&rsquo;en paient pas. Vous n&rsquo;allez quand m\u00eame pas leur dire que ce sont les \u00a0\u00bb socialos \u00a0\u00bb qui ont voulu de telles mesures fiscales !!!<\/p>\n<p>Vous vous attaquez aux d\u00e9rives de la finance qui devient \u00a0\u00bb le profitariat \u00ab\u00a0. Mazette, elle est bien bonne celle-l\u00e0. Une chance 3que vous \u00eates l\u00e0 pour nous le dire, nous ne l&rsquo;avions pas remarqu\u00e9 ! Dites un peu, Monsieur Charles, vous ne l&rsquo;avouez pas mais la finance d&rsquo;aujourd&rsquo;hui n&rsquo;est jamais que le r\u00e9sultat d&rsquo;une d\u00e9r\u00e9gulation des march\u00e9s que les lib\u00e9raux ont toujours pr\u00f4n\u00e9e. Loin de moi l&rsquo;id\u00e9e de vous consid\u00e9rer comme les seuls responsables mais vous en \u00eates cependant les principaux artisans politiques.<\/p>\n<p>Vous essayez Monsieur Charles, bien maladroitement il me semble, de donner \u00e0 votre \u00a0\u00bb mouvement \u00a0\u00bb des accents sociaux qu&rsquo;il n&rsquo;a pas. Vous trompez les citoyens en reprenant \u00e0 votre compte une comm\u00e9moration dans laquelle vous n&rsquo;avez rien \u00e0 faire. Le 1er mai ne vous appartiendra jamais, pas plus que la f\u00eate de la Communaut\u00e9 Wallonie Bruxelles n&rsquo;appartiendra \u00e0 la NVA ou la Gay Pride au Vlaams Belang. C&rsquo;est une question d&rsquo;identit\u00e9. Augustin Spies, un des condamn\u00e9s am\u00e9ricains en 1886 lors des gr\u00e8ves pour l&rsquo;instauration des 8 heures, a dit \u00ab\u00a0Le jour viendra o\u00f9 notre silence sera plus puissant que les voix que vous \u00e9tranglez aujourd&rsquo;hui\u00a0\u00bb1 ne brisez pas ce silence Monsieur Charles, respectez le.<\/p>\n<p>Si votre parti et les gens qui le composent ont des valeurs fondamentales, ce dont je doute souvent, je vous invite \u00e0 faire la f\u00eate pour c\u00e9l\u00e9brer ces valeurs. Ce sera l\u00e9gitime, utile pour vous et les v\u00f4tres. Cela vous donnera une v\u00e9ritable identit\u00e9 et enrichira le d\u00e9bat. Vous pourriez f\u00eater le lib\u00e9ralisme, \u00e0 Jodoigne ou ailleurs, \u00e0 Wavre par exemple. Je vous propose une date : le 29 ao\u00fbt. Vous f\u00eaterez la naissance de John Locke (29.08.1632), ce philosophe anglais qui est un des p\u00e8res du lib\u00e9ralisme. Ce serait une bonne date pour galvaniser tous ceux qui veulent \u00a0\u00bb bosser \u00a0\u00bb apr\u00e8s les grandes vacances.<\/p>\n<p><b>Eric VERMEERSCH Mai 2012<\/b><\/p>\n<p>( Extrait du n\u00b0 90 de \u00ab\u00a0Secouez-vous les Id\u00e9es\u00a0\u00bb publi\u00e9 par le <b>CESEP<\/b> &#8211; Centre Socialiste d\u2019Education Permanente ASBL \u2013 )<\/p>\n<p><strong><font color=\"#ff0000\"><em>Texte reproduit avec l\u2019autorisation de l\u2019auteur<\/em><\/font><\/strong><br \/>\n<b><u>Pour contacter le CESEP<\/u> :<\/b><\/p>\n<p><b> Centre Socialiste d\u2019Education Permanente ASBL<\/b><br \/>\nrue de Charleroi, 47 \u00e0 1400 Nivelles<br \/>\nt\u00e9l. : 067\/219 468 &#8211; 067\/890 866<br \/>\nFax : 067\/210 097<br \/>\nCourriel : <a href=\"mailto:infos@cesep.be\">infos@cesep.be<br \/>\n<\/a> Site : <a href=\"http:\/\/www.cesep.be\">www.cesep.be<\/a><br \/>\nVotre avis : <a href=\"mailto:secouezvouslesidees@cesep.be\">secouezvouslesidees@cesep.be<\/a><\/p>\n<p><b>Pour consulter le n\u00b0 90 de \u00ab\u00a0<i>Secouez-vous les Id\u00e9es<\/i>\u00a0\u00bb dans son int\u00e9gralit\u00e9 : <a href=\"http:\/\/www.cesep.be\/SERVICES\/PERIODIQUES\/SECOUEZ_90.pdf\">Cliquez ICI<\/a><\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>( Edito de &lsquo;Secouez-vous les id\u00e9es&rsquo; n\u00b0 90 juin juillet ao\u00fbt 2012 &#8211; CESEP &#8211; info@cesep.be) Monsieur Charles, Franchement, sinc\u00e8rement, j&rsquo;envie votre papa. Qu&rsquo;il doit \u00eatre doux pour ce p\u00e8re Louis de ressentir un tel respect filial. Avoir un fils &hellip; <a href=\"https:\/\/denis-meunier.be\/Deonisios\/2012\/07\/02\/le-1er-mai\/\">Continuer la lecture <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-134","post","type-post","status-publish","format-standard","hentry","category-les-textes-que-jaime"],"_links":{"self":[{"href":"https:\/\/denis-meunier.be\/Deonisios\/wp-json\/wp\/v2\/posts\/134","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/denis-meunier.be\/Deonisios\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/denis-meunier.be\/Deonisios\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/denis-meunier.be\/Deonisios\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/denis-meunier.be\/Deonisios\/wp-json\/wp\/v2\/comments?post=134"}],"version-history":[{"count":1,"href":"https:\/\/denis-meunier.be\/Deonisios\/wp-json\/wp\/v2\/posts\/134\/revisions"}],"predecessor-version":[{"id":885,"href":"https:\/\/denis-meunier.be\/Deonisios\/wp-json\/wp\/v2\/posts\/134\/revisions\/885"}],"wp:attachment":[{"href":"https:\/\/denis-meunier.be\/Deonisios\/wp-json\/wp\/v2\/media?parent=134"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/denis-meunier.be\/Deonisios\/wp-json\/wp\/v2\/categories?post=134"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/denis-meunier.be\/Deonisios\/wp-json\/wp\/v2\/tags?post=134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}