{"id":1006,"date":"2020-07-31T20:56:35","date_gmt":"2020-07-31T18:56:35","guid":{"rendered":"https:\/\/denis-meunier.be\/Deonisios\/?p=1006"},"modified":"2020-07-31T20:58:13","modified_gmt":"2020-07-31T18:58:13","slug":"est-ce-le-moment-de-polemiquer","status":"publish","type":"post","link":"https:\/\/denis-meunier.be\/Deonisios\/2020\/07\/31\/est-ce-le-moment-de-polemiquer\/","title":{"rendered":"Est-ce le moment de pol\u00e9miquer ?"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"472\" height=\"342\" src=\"https:\/\/denis-meunier.be\/Deonisios\/wp-content\/uploads\/2020\/07\/BartDeWever.jpg\" alt=\"\" class=\"wp-image-1007\" srcset=\"https:\/\/denis-meunier.be\/Deonisios\/wp-content\/uploads\/2020\/07\/BartDeWever.jpg 472w, https:\/\/denis-meunier.be\/Deonisios\/wp-content\/uploads\/2020\/07\/BartDeWever-300x217.jpg 300w\" sizes=\"auto, (max-width: 472px) 100vw, 472px\" \/><\/figure>\n\n\n\n<p>Certains n&rsquo;ont-ils vraiment pas autre chose \u00e0 faire que de rechercher la paille dans l\u2019\u0153il du voisin pour cacher la poutre qui leur barre la vue  !<\/p>\n\n\n\n<p class=\"has-medium-font-size\">A l&rsquo;heure actuelle n&rsquo;y a-t-il rien de plus urgent ?<\/p>\n\n\n\n<p><strong>Prot\u00e9gez-vous<\/strong><br>On n&rsquo;est pas sorti de l&rsquo;auberge !<br>C&rsquo;est ridicule de faire la chasse aux sorci\u00e8res.<br>En temps utile on tirera les conclusions !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Certains n&rsquo;ont-ils vraiment pas autre chose \u00e0 faire que de rechercher la paille dans l\u2019\u0153il du voisin pour cacher la poutre qui leur barre la vue  ! <a href=\"https:\/\/denis-meunier.be\/Deonisios\/2020\/07\/31\/est-ce-le-moment-de-polemiquer\/\">Continuer la lecture <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":1007,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-1006","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-je-rale"],"_links":{"self":[{"href":"https:\/\/denis-meunier.be\/Deonisios\/wp-json\/wp\/v2\/posts\/1006","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/denis-meunier.be\/Deonisios\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/denis-meunier.be\/Deonisios\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/denis-meunier.be\/Deonisios\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/denis-meunier.be\/Deonisios\/wp-json\/wp\/v2\/comments?post=1006"}],"version-history":[{"count":1,"href":"https:\/\/denis-meunier.be\/Deonisios\/wp-json\/wp\/v2\/posts\/1006\/revisions"}],"predecessor-version":[{"id":1008,"href":"https:\/\/denis-meunier.be\/Deonisios\/wp-json\/wp\/v2\/posts\/1006\/revisions\/1008"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/denis-meunier.be\/Deonisios\/wp-json\/wp\/v2\/media\/1007"}],"wp:attachment":[{"href":"https:\/\/denis-meunier.be\/Deonisios\/wp-json\/wp\/v2\/media?parent=1006"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/denis-meunier.be\/Deonisios\/wp-json\/wp\/v2\/categories?post=1006"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/denis-meunier.be\/Deonisios\/wp-json\/wp\/v2\/tags?post=1006"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}